 {"id":20676,"date":"2020-07-22T00:00:00","date_gmt":"2022-09-05T19:03:44","guid":{"rendered":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/6450\/"},"modified":"2022-09-15T12:02:02","modified_gmt":"2022-09-15T15:02:02","slug":"6450","status":"publish","type":"circulares","link":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/6450\/","title":{"rendered":"Circular Nro. 103\/2020:&#8221;Llamado a concurso cerrado para cubrir 30 cargos de Oficiales Notificadores suplentes para la sede judicial Rosario &#8211; 2do. llamado&#8221;"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-circulares pdfprnt-top-right\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20676?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20676?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p><u><strong>&#8220;Circular Nro. 103 \/20.-<\/strong><\/u><\/p>\n<p>Santa Fe, 22 de julio de 2020.-<\/p>\n<p>Se\u00f1or<br \/>\nTitular del \u00d3rgano Jurisdiccional<br \/>\n<u>S \/ D<\/u><\/p>\n<div style=\"text-align: justify;\">\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia de fecha 16 de julio de 2020, se ha dispuesto llamar a Concurso para la provisi\u00f3n de los siguientes cargos:<br \/>\n\u201cRosario, 16 de julio de 2020. <u>VISTO<\/u>: El llamado a Concurso para cubrir treinta cargos de Oficiales Notificadores Suplentes para los Tribunales de Rosario dispuesto seg\u00fan Resoluci\u00f3n N\u00b0 228 del 25.06.2020; y <u>CONSIDERANDO<\/u>: las necesidades del servicio judiciario; las prescripciones del Reglamento de las Oficinas de Mandamientos y Notificaciones de los Tribunales de la Provincia, aprobado por Acuerdo de esta Corte de fecha 09.06.99, Acta 20, punto 13; sus modificatorias seg\u00fan Acuerdo del 05.04.2011, Acta N\u00b0 15, punto 7, especialmente el art\u00edculo 21; las necesidades del servicio judiciario; por ello y teniendo en cuenta lo establecido en los art\u00edculos 92 de la Constituci\u00f3n Provincial, 19 y 22 de la Ley Nro.10.160 (t.o. seg\u00fan Decreto Nro. 0046\/98) y las facultades conferidas por Acuerdo de fecha 20.10.99, Acta N\u00b0 41, punto \u00fanico, la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia de Santa Fe, <u>RESUELVE<\/u>: I) Proceder a realizar un segundo llamado a inscripci\u00f3n en el Concurso para la cobertura de treinta cargos de Oficiales Notificadores Suplentes en los Tribunales de Rosario, teniendo en cuenta que los postulantes inscriptos en el primer llamado no alcanzaron a cubrir las vacantes existentes. II) Establecer que, excepcionalmente, podr\u00e1n participar del Concurso cerrado y de oposici\u00f3n, los interesados de la mencionada sede que re\u00fanan los siguientes requisitos: a) una antig\u00fcedad como empleado titular de un (1) a\u00f1o calendario anterior al de la fecha del llamado a concurso, si se tratare de empleados administrativos y dos (2) a\u00f1os de antig\u00fcedad como titulares y ciclo b\u00e1sico aprobado cuando el interesado integrare la planta del Personal Obrero, de Maestranza y Servicios; b) antecedentes personales y de idoneidad para el desempe\u00f1o de la funci\u00f3n, lo que se acreditar\u00e1 mediante examen de oposici\u00f3n que versar\u00e1 sobre conocimientos del cap\u00edtulo de notificaciones del C\u00f3digo Procesal Civil y Comercial y toda otra norma legal o reglamentaria referente en la materia. III) Fijar como per\u00edodo de inscripci\u00f3n el comprendido entre el 27 y el 29 de julio del corriente a\u00f1o, ambas fechas inclusive, debiendo presentar las respectivas solicitudes en la Secretar\u00eda Letrada del Cuerpo en Rosario. IV) Establecer como fecha para la recepci\u00f3n del citado examen, el d\u00eda 12 de agosto de 2020, a partir de las 9 horas, en la Secretar\u00eda de la Corte en Rosario. V) Disponer que el programa sobre el que versar\u00e1 el examen, es el aprobado por el Alto Cuerpo en Acuerdo de fecha 22.11.95, Acta N\u00b042, punto 3\u00b0. Reg\u00edstrese, h\u00e1gase saber y oportunamente d\u00e9se cuenta al cuerpo. FDO.: BORDAS (SECRETARIO). FALCONI (PROSECRETARIO)\u201d.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Saludo a Ud. atentamente.<\/p>\n<\/div>\n<p>Fdo: Dr. Eduardo Bordas<br \/>\n(Secretario de Gobierno)&#8221;<\/p>\n<p><a title=\"Ver archivo\" href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2020\/07\/6653.pdf\" target=\"_blank\" rel=\"noopener\">CI-103-2020 &#8211; Formulario Concurso 30 Oficiales Notificadores Suplentes Rosario 2020 (2\u00b0 llamado)<\/a><\/p>\n<p>&nbsp;<\/p>\n<div class=\"gsp_post_data\" data-post_type=\"circulares\" data-cat=\"anio-2020\" data-modified=\"120\" data-title=\"Circular Nro. 103\/2020:&#8221;Llamado a concurso cerrado para cubrir 30 cargos de Oficiales Notificadores suplentes para la sede judicial Rosario &#8211; 2do. llamado&#8221;\" data-home=\"https:\/\/www.justiciasantafe.gov.ar\"><\/div>","protected":false},"excerpt":{"rendered":"<p>&#8220;Circular Nro. 103 \/20.- Santa Fe, 22 de julio de 2020.- Se\u00f1or Titular del \u00d3rgano Jurisdiccional S \/ D \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de [&#8230;]\n","protected":false},"author":10,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-20676","circulares","type-circulares","status-publish","format-standard","hentry","category-anio-2020"],"acf":{"i2t_anio":2020,"i2t_id_historico":6450,"i2t_autor_historico":"lcarrivale"},"_links":{"self":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares"}],"about":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/circulares"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20676\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=20676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=20676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=20676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}