 {"id":20689,"date":"2020-07-06T00:00:00","date_gmt":"2022-09-05T19:03:47","guid":{"rendered":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/6423\/"},"modified":"2022-09-15T12:07:07","modified_gmt":"2022-09-15T15:07:07","slug":"6423","status":"publish","type":"circulares","link":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/6423\/","title":{"rendered":"Circular nro. 85.  Cese del asueto administrativo en la ciudad de Ceres, en el marco de las medidas dispuestas por el COVID-19"},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-circulares pdfprnt-top-right\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20689?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20689?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p><strong>Circular Nro. 85\/20<\/strong><\/p>\n<p>Santa Fe, 6 de julio de 2020<\/p>\n<p>Se\u00f1or<br \/>\nTitular del \u00d3rgano Jurisdiccional<br \/>\n<u>S \/ D<\/u><\/p>\n<p>Me dirijo a Ud. a fin de comunicarle, para su conocimiento y notificaci\u00f3n a todos los integrantes de ese \u00f3rgano jurisdiccional, lo dispuesto por la Presidencia de la Corte Suprema de Justicia:<br \/>\n\u201cSanta Fe, 6 de julio de 2020. &#8220;<u>SITUACI\u00d3N EPIDEMIOL\u00d3GICA MUNDIAL GENERADA A RA\u00cdZ DE LA ENFERMEDAD COVID-19 (CORONAVIRUS).<\/u> <u>VISTAS:<\/u> Las actuaciones caratuladas \u201cSecretar\u00eda de Gobierno de la Corte Suprema de Justicia de Santa Fe S\/ Medidas Preventivas de Salud COVID-19 (Coronavirus)\u201d CUIJ N\u00b0 21-17613628-3, en el marco del estado de emergencia sanitaria dispuesto por Decreto de Necesidad y Urgencia del Poder Ejecutivo de la Naci\u00f3n N\u00b0 260 de fecha 12.3.2020; y, <u>CONSIDERANDO<\/u>: Que el pasado 19 de junio del corriente se confirmaron en la ciudad de Ceres, Departamento San Crist\u00f3bal, varios casos positivos de coronavirus Covid-19; hecho que motiv\u00f3 el dictado de la Resoluci\u00f3n Ministerial Nro. 167\/20 por parte del Poder Ejecutivo Provincial. Que, en dicha decisi\u00f3n, la Administraci\u00f3n Central dispuso, entre otras medidas, declarar a partir de la referida fecha en cuarentena sanitaria a la Ciudad de Ceres; suspender, dentro del \u00e1mbito de la citada localidad y con car\u00e1cter preventivo, las excepciones al &#8220;aislamiento social, preventivo y obligatorio&#8221; y la prohibici\u00f3n de circular que se habilitaran por los Decretos Nros. 0367\/20, 0382\/20, 0393\/20, 0414\/20, 0436\/20, 0446\/20, 0449\/20, 0455\/20 y 0456\/20 art\u00edculo 2\u00b0 del Poder Ejecutivo y dem\u00e1s legislaci\u00f3n dictada en id\u00e9ntico sentido, hasta tanto la autoridad sanitaria aconseje lo contrario; e inst\u00f3 a la poblaci\u00f3n de la ciudad a permanecer en sus domicilios respetando el &#8220;aislamiento social, preventivo y obligatorio&#8221; y la prohibici\u00f3n de circular mientras dure la medida dispuesta, limitando sus desplazamientos a los estrictamente necesarios. Que, por consiguiente, y de conformidad al criterio oportunamente adoptado por esta Corte de alinear sus decisiones en virtud de las medidas que adopten los organismos nacionales y provinciales en relaci\u00f3n a la contenci\u00f3n de la pandemia que enfrentamos, se dispuso por Resoluci\u00f3n de Presidencia Nro. 597 de fecha 22.6.20 el receso administrativo en todo el \u00e1mbito de la localidad de Ceres, desde el 22 de junio de 2020 y hasta tanto las autoridades sanitarias competentes, por medio del Poder Ejecutivo Provincial, recomienden su reanudaci\u00f3n. Que dicha decisi\u00f3n implic\u00f3, entre otras medidas, retrotraer las condiciones de prestaci\u00f3n del servicio a un esquema de trabajo direccionado a cuestiones de urgente despacho y que por su naturaleza no pod\u00edan ser susceptibles de espera o reprogramaci\u00f3n, suspendiendo a su vez los plazos procesales y la celebraci\u00f3n de audiencias. Asimismo, se dio continuidad a la factibilidad con que cuentan todos los profesionales de la provincia, de presentar sus escritos o demandas por v\u00eda digital a los correos electr\u00f3nicos de las unidades jurisdiccionales de dicha sede. Que el pasado 3.7.20 el Ministerio de Gesti\u00f3n P\u00fablica de la provincia, mediante Resoluci\u00f3n Nro. 194\/20 dispuso en su ART\u00cdCULO 1\u00b0 lo siguiente: \u201cA partir del dictado del presente decreto cobrar\u00e1n plena vigencia en el \u00e1mbito de la ciudad de Ceres, Departamento San Crist\u00f3bal, las excepciones al &#8220;aislamiento social, preventivo y obligatorio&#8221; y la prohibici\u00f3n de circular que durante su vigencia se dispusieran por los Decretos Nros. 0367\/20, 0382\/20, 0393\/20, 0414\/20, 0436\/20, 0446\/20, 0449\/20, 0455\/20 y 0456\/20 art\u00edculo 2\u00b0 de \u00e9ste Poder Ejecutivo; quedando en consecuencia habilitadas, con las condiciones establecidas en los mismos en cada caso, las siguientes actividades: 1.comercio minorista de venta de mercader\u00edas, 2. actividad industrial, 3.obras privadas, 4. actividades de cobranza a domicilio, 5. talleres mec\u00e1nicos, lavaderos y servicios de mantenimiento y reparaci\u00f3n de autom\u00f3viles y motoveh\u00edculos, 6. ejercicio de profesiones liberales, incluidos mandatarios, corredores y martilleros debidamente matriculados e inscriptos 7.actividad inmobiliaria 8. mudanzas 9. servicios de peluquer\u00eda, manicur\u00eda, cosmetolog\u00eda y podolog\u00eda, 10.actividades de las Asociaciones y Agencias para el Desarrollo o entidades de similar objeto, 11.Actividad aseguradora, 12. Permisionarios (agentes y subagentes) de la Caja de Asistencia Social \u2014 Loter\u00eda de Santa Fe, 13.Salidas breves para caminatas de esparcimiento, en beneficio de la salud y el bienestar psicof\u00edsico, 14. actividades religiosas individuales en iglesias, templos y lugares de culto de cercan\u00eda, correspondientes a la Iglesia Cat\u00f3lica Apost\u00f3lica Romana y entidades religiosas inscriptas en el Registro Nacional de Cultos, las que en ning\u00fan caso podr\u00e1n consistir en la celebraci\u00f3n de ceremonias que impliquen reuni\u00f3n de personas, 15.Sindicatos, entidades gremiales empresarias, obras sociales, cajas y colegios profesionales, administraci\u00f3n de entidades deportivas, 16. Actividad de locales gastron\u00f3micos (bares, restaurantes, rotiser\u00edas, helader\u00edas, y otros de venta de productos alimenticios elaborados), exclusivamente con la modalidad &#8220;para llevar&#8221; (tambi\u00e9n llamada &#8220;take away&#8221;)\u201d. Que as\u00ed las cosas, y ante el nuevo escenario planteado, se estima prudente adoptar las medidas de gobierno necesarias para reconducir la prestaci\u00f3n del servicio de justicia en la referida localidad, de conformidad al esquema de trabajo puesto en marcha por esta Corte mediante Acta Acuerdo Nro. 14, Punto 1 del 13.5.20, y que se encontraba vigente en la localidad de Ceres hasta el dictado de la Resoluci\u00f3n Ministerial Nro. 167\/20 por parte del Poder Ejecutivo Provincial. Que, en raz\u00f3n de ello, esta Presidencia de conformidad a las previsiones del art\u00edculo 22, inc. 9, de la ley 10.160 (t.o seg\u00fan decreto N\u00b0 49\/98). <u>RESUELVE<\/u>: I. Disponer el cese del receso administrativo en todo el \u00e1mbito de la localidad de Ceres, como as\u00ed tambi\u00e9n la rehabilitaci\u00f3n de los plazos procesales y la celebraci\u00f3n de audiencias a partir del 7.7.20. II. Disponer la reanudaci\u00f3n de la actividad judicial en dicha sede, de conformidad a lo resuelto por la Corte Suprema de Justicia mediante Acta Acuerdo Nro. 14, Punto 1 del 13.5.20. III. Instruir a la Secretar\u00eda de Gobierno a los fines de que adopte las medidas necesarias y que crea corresponder en orden a resolver las situaciones que se presenten en relaci\u00f3n al tema. IV. Poner de manifiesto que las decisiones aqu\u00ed adoptadas, en el contexto de crisis y estado de emergencia sanitaria establecido por el Poder Ejecutivo Nacional, se enmarcan en la continua b\u00fasqueda de la primordial preservaci\u00f3n de la salud de los integrantes de este Poder Judicial; auxiliares de la justicia; y p\u00fablico en general, y de la m\u00e1s adecuada prestaci\u00f3n posible del servicio de justicia; hecho que habilita su constante y prudente revisi\u00f3n si las circunstancias sanitarias as\u00ed lo aconsejaren. V. Hacer saber lo aqu\u00ed dispuesto al Poder Ejecutivo Provincial, al Poder Legislativo de la Provincia a trav\u00e9s de las Honorables C\u00e1maras de Senadores y Diputados, al Ministerio P\u00fablico de la Acusaci\u00f3n, al Servicio P\u00fablico Provincial de Defensa Penal, a los Colegios Profesionales de Abogados y Procuradores de las cinco Circunscripciones Judiciales, al Colegio de Magistrados y Funcionarios y al Sindicato de Trabajadores Judiciales. VI.- Brindar la m\u00e1s amplia difusi\u00f3n del presente decisorio a trav\u00e9s de los medios correspondientes. FDO. GUTI\u00c9RREZ. (PRESIDENTE). BORDAS (SECRETARIO DE GOBIERNO)&#8221;.<\/p>\n<p>Saludo a Ud. atentamente.<\/p>\n<p>Dr. Eduardo Bordas<br \/>\nSecretario Corte Suprema<\/p>\n<div class=\"gsp_post_data\" data-post_type=\"circulares\" data-cat=\"anio-2020\" data-modified=\"120\" data-title=\"Circular nro. 85.  Cese del asueto administrativo en la ciudad de Ceres, en el marco de las medidas dispuestas por el COVID-19\" data-home=\"https:\/\/www.justiciasantafe.gov.ar\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Circular Nro. 85\/20 Santa Fe, 6 de julio de 2020 Se\u00f1or Titular del \u00d3rgano Jurisdiccional S \/ D Me dirijo a Ud. a fin de comunicarle, para su conocimiento y notificaci\u00f3n a todos los integrantes de ese \u00f3rgano jurisdiccional, lo dispuesto por la Presidencia de la Corte Suprema de Justicia: \u201cSanta Fe, 6 de julio [&#8230;]\n","protected":false},"author":10,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-20689","circulares","type-circulares","status-publish","format-standard","hentry","category-anio-2020"],"acf":{"i2t_anio":2020,"i2t_id_historico":6423,"i2t_autor_historico":"lcarrivale"},"_links":{"self":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares"}],"about":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/circulares"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":0,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/20689\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=20689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=20689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=20689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}