 {"id":39804,"date":"2024-03-18T13:19:06","date_gmt":"2024-03-18T16:19:06","guid":{"rendered":"https:\/\/www.justiciasantafe.gov.ar\/?post_type=circulares&#038;p=39804"},"modified":"2024-03-18T13:19:06","modified_gmt":"2024-03-18T16:19:06","slug":"circular-nro-18-llamado-a-concurso-de-oficiales-notificadores-suplentes","status":"publish","type":"circulares","link":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/circular-nro-18-llamado-a-concurso-de-oficiales-notificadores-suplentes\/","title":{"rendered":"Circular nro. 18. Llamado a concurso de Oficiales Notificadores Suplentes."},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-circulares pdfprnt-top-right\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/39804?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/pdf.png?357112440\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/39804?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/print.png?1674575983\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p align=\"RIGHT\"><span style=\"color: #000000\"><u><b>Circular N\u00b0 18\/24.-<\/b><\/u><\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"RIGHT\"><span style=\"color: #000000\">Santa Fe, 18 de marzo de 2024.-<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Se\u00f1or<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Titular del \u00d3rgano Jurisdiccional<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u>S \/ D<\/u><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"> Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia, ratificada por Acuerdo N\u00b0 7, punto 1, celebrado el d\u00eda 14 de marzo de 2024, se ha dispuesto lo siguiente: \u201c<\/span><span style=\"color: #000000\"><span lang=\"es-ES\">Santa Fe, 12 de marzo de 2024. <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\"><u>VISTAS<\/u><\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">: <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">Las actuaciones caratuladas \u201cCONCURSO DE OFICIALES NOTIFICADORES\u201d, (CUIJ 21-17491057-7), las necesidades del servicio judiciario; y, <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\"><u>CONSIDERANDO<\/u><\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">: Que teniendo en cuenta los antecedentes inmediatos en la materia, como as\u00ed tambi\u00e9n el relevamiento llevado a cabo por esta Secretar\u00eda de Gobierno, del cual se desprende la escasa participaci\u00f3n de agentes inscriptos a los sucesivos concursos de Oficiales Notificadores llevados a cabo en las sedes judiciales de Esperanza, San Jorge, Reconquista, Vera, Tostado y San Crist\u00f3bal; y en procura de optimizar los recursos disponibles y evitar el consiguiente desgaste administrativo, y de modo excepcional, establecer como requisito para la inscripci\u00f3n en el presente, que el aspirante revista como agente titular en los referidos Tribunales. (v. Art\u00edculo 1 del Reglamento para las Oficinas de Mandamientos y Notificaciones &#8211; Acta 20, p. 13 del 9.6.1999 y modificatorias). Que atento ello, y teniendo en cuenta lo establecido en los art\u00edculos 92 de la Constituci\u00f3n Provincial, 19 y 22 de la ley 10.160 (t.o. seg\u00fan decreto 0046\/98) y las facultades conferidas por Acuerdo de fecha 20.10.1999, Acta N\u00b0 41, punto \u00fanico, la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia de Santa Fe, <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\"><u>RESUELVE<\/u><\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">: I. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">dos cargos de Oficiales Notificadores Suplentes para los Tribunales de Esperanza<\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">. <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">II. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir un cargo de Oficial Notificador Suplente para los Tribunales de San Jorge. III. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir dos cargos de Oficiales Notificadores Suplentes para los Tribunales de Vera. IV. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir tres cargos de Oficiales Notificadores Suplentes para los Tribunales de Reconquista. V. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir un cargo de Oficial Notificador Suplente para los Tribunales de Tostado. VI. Llamar a concurso cerrado y de oposici\u00f3n, para cubrir dos cargos de Oficiales Notificadores Suplentes para los Tribunales de San Crist\u00f3bal. <\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">VII. Establecer que podr\u00e1n participar del Concurso, los interesados que re\u00fanan los siguientes requisitos: a) agentes titulares de dichas sedes judiciales; y b) antecedentes personales y de idoneidad para el desempe\u00f1o de la funci\u00f3n, lo que se acreditar\u00e1 mediante el examen de oposici\u00f3n correspondiente. VIII. Fijar como per\u00edodo de inscripci\u00f3n el comprendido entre e<\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\">l 25 de marzo y el 5 de abril<\/span><\/span><span style=\"color: #000000\"><span lang=\"es-ES\"> del a\u00f1o 2024, ambas fechas inclusive, debiendo presentarse las respectivas solicitudes en la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia en Santa Fe. IX. Disponer que oportunamente se fijar\u00e1n las fechas de realizaci\u00f3n de los ex\u00e1menes de oposici\u00f3n a los postulantes que cumplimenten las exigencias legales y reglamentarias. X. Establecer que el programa sobre el que versar\u00e1 el examen, es el aprobado por este Cuerpo en Acuerdo de fecha 22.11.95, Acta N\u00b0 42, punto 3\u00b0. Reg\u00edstrese, h\u00e1gase saber y dese cuenta al Cuerpo.<\/span><\/span> <span style=\"color: #000000\">FDO.: BORDAS (SECRETARIO DE GOBIERNO). GOMEZ (PROSECRETARIO DE GOBIERNO)\u201d.<\/span><span style=\"color: #000000\"> &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"> Saludo a Ud. atentamente.<\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">Dr. Eduardo Bordas<\/p>\n<p align=\"JUSTIFY\">Secretario de Gobierno<\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">Formularios de inscripc\u00ed\u00f3n:<\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-1-Esperanza.pdf\" target=\"\" rel=\"attachment wp-att-39806 noopener\">CIRC-18-24 ANEXO 1-Esperanza<\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-2-San-jorge.pdf\" target=\"\" rel=\"attachment wp-att-39807 noopener\">CIRC-18-24 ANEXO 2-San jorge<\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-3-Vera.pdf\" target=\"\" rel=\"attachment wp-att-39808 noopener\">CIRC-18-24 ANEXO 3-Vera<\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-4-Reconquista.pdf\" target=\"\" rel=\"attachment wp-att-39809 noopener\">CIRC-18-24 ANEXO 4-Reconquista<\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-5-Tostado.pdf\" target=\"\" rel=\"attachment wp-att-39810 noopener\">CIRC-18-24 ANEXO 5-Tostado<\/a><\/p>\n<p align=\"JUSTIFY\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/03\/CIRC-18-24-ANEXO-6.pdf\" target=\"\" rel=\"attachment wp-att-39811 noopener\">CIRC-18-24 ANEXO 6<\/a><\/p>\n<div class=\"gsp_post_data\" data-post_type=\"circulares\" data-cat=\"ano-2024-circulares,circulares\" data-modified=\"120\" data-title=\"Circular nro. 18. Llamado a concurso de Oficiales Notificadores Suplentes.\" data-home=\"https:\/\/www.justiciasantafe.gov.ar\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Circular N\u00b0 18\/24.- Santa Fe, 18 de marzo de 2024.- Se\u00f1or Titular del \u00d3rgano Jurisdiccional S \/ D Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia, [&#8230;]\n","protected":false},"author":72,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4113,18],"tags":[],"class_list":["post-39804","circulares","type-circulares","status-publish","format-standard","hentry","category-ano-2024-circulares","category-circulares"],"acf":{"i2t_anio":2024,"i2t_id_historico":"","i2t_autor_historico":""},"_links":{"self":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/39804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares"}],"about":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/circulares"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/72"}],"version-history":[{"count":0,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/39804\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=39804"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=39804"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=39804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}