 {"id":41344,"date":"2024-06-12T13:22:59","date_gmt":"2024-06-12T16:22:59","guid":{"rendered":"https:\/\/www.justiciasantafe.gov.ar\/?post_type=circulares&#038;p=41344"},"modified":"2024-06-12T13:22:59","modified_gmt":"2024-06-12T16:22:59","slug":"circular-nro-57-ultima-etapa-de-digitalizacion-integral-del-poder-judicial","status":"publish","type":"circulares","link":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/circular-nro-57-ultima-etapa-de-digitalizacion-integral-del-poder-judicial\/","title":{"rendered":"Circular nro. 57. \u00daltima etapa de Digitalizaci\u00f3n Integral del Poder Judicial."},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-circulares pdfprnt-top-right\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/41344?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/41344?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p align=\"RIGHT\"><span style=\"color: #000000\"><span style=\"font-family: CG Times, Times New Roman, serif\"><u><b>Circular Nro. 57\/24.-<\/b><\/u><\/span><\/span><\/p>\n<p align=\"RIGHT\"><span style=\"color: #000000\"> <span style=\"font-family: CG Times, Times New Roman, serif\">Santa Fe, 12 de junio de 2024.-<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: CG Times, Times New Roman, serif\">Se\u00f1or <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: CG Times, Times New Roman, serif\">Titular del \u00d3rgano Jurisdiccional<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: CG Times, Times New Roman, serif\"><u>S \/ D<\/u><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span lang=\"es-ES\">Me dirijo a Ud. a fin de comunicarle, para su conocimiento y notificaci\u00f3n a todos los integrantes de ese \u00f3rgano jurisdiccional, que en el Acuerdo celebrado el d\u00eda 11.6.2024<\/span><\/span><\/span><span style=\"font-family: Times New Roman, serif\"><span lang=\"es-ES\">, Acta N\u00b0 21, la Corte<\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span lang=\"es-ES\"> Suprema de Justicia de la Provincia de Santa Fe, adopt\u00f3 el siguiente decisorio:<\/span><\/span><\/span><\/p>\n<p lang=\"es-ES\" align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"> \u201c<\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\"><u>RESOLUCI\u00d3N DE LA SECRETAR\u00cdA DE GOBIERNO DE LA CORTE SUPREMA DE JUSTICIA REF. \u00daLTIMA ETAPA DE DIGITALIZACI\u00d3N INTEGRAL DEL PODER JUDICIAL<\/u><\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">: El se\u00f1or Secretario de Gobierno de la Corte Suprema de Justicia de la Provincia informa que en fecha 7 de junio del corriente a\u00f1o, dict\u00f3 la siguiente resoluci\u00f3n: \u201c\u2026.<\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\"><u>VISTAS<\/u><\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">: Las necesidades de servicio judicial, y; <\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\"><u>CONSIDERANDO<\/u><\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">: Que desde el a\u00f1o 2022, el Alto Cuerpo puso en marcha un ambicioso proyecto de digitalizaci\u00f3n de procesos en el \u00e1mbito de la justicia de derecho privado. Que en este sentido, por Acta Acuerdo Nro. 47, Punto 27 de fecha 20.12.22; Acta Acuerdo Nro. 15, Punto 9 de fecha 23.5.23; Acta Acuerdo Nro. 19, Punto 27 de fecha 27.06.23; Acta Acuerdo Nro. 28, Punto 05 de fecha 30.08.23; Acta Acuerdo Nro. 34, Punto 10 de fecha 10.10.23; Acta Acuerdo Nro. 39, Punto 8 de fecha 21.11.23; y Acta Acuerdo Nro. 43, Punto 28 de fecha 12.12.23, se implement\u00f3 de manera gradual pero sostenida, un programa que provoc\u00f3 la materializaci\u00f3n de la experiencia digital en todas y cada una de las unidades jurisdiccionales de la provincia. As\u00ed, en todo el mapa judicial, y en variadas materias, los Juzgados y Tribunales de todas las instancias llevaron adelante -y lo siguen haciendo- los procesos en sus respectivos \u00e1mbitos de competencia con el soporte inform\u00e1tico, y en virtud de los reglamentos dictados al efecto por ese Alto Cuerpo. Que, en lo que ahora interesa, y teniendo en cuenta el \u00f3ptimo desempe\u00f1o que las decisiones adoptadas vienen demostrando, se entiende oportuno proponer la implementaci\u00f3n integral de la experiencia digital a todos los expedientes de todas las unidades jurisdiccionales de los distintos fueros de derecho privado de este Poder Judicial, que se inicien en una fecha determinada. Que, de esta manera, se concretar\u00e1 el inicio de la \u00faltima etapa de la digitalizaci\u00f3n integral del Poder Judicial; la cual permitir\u00e1 contar con toda la informaci\u00f3n bajo una moderna l\u00f3gica de trabajo, resguardada en servidores propios y con un \u00fanico sistema de gesti\u00f3n aplicable a toda la provincia. Ahora bien, en miras a efectuar una correcta puesta en marcha de esta \u00faltima etapa, que contemple las variables inherentes a todo emprendimiento, se considera prudente efectuar su materializaci\u00f3n en forma escalonada, agrupando fueros y materias de acuerdo a criterios deliberados y consensuados con las \u00e1reas intervinientes. En este orden de ideas, se detallan a continuaci\u00f3n las etapas de implementaci\u00f3n con las respectivas unidades involucradas: Etapa 1: A implementarse el 22.7.2024, comprende a los expedientes que se inicien en dicha fecha en las C\u00e1maras de Apelaci\u00f3n de Circuito de Santa Fe y Rosario, los Juzgados de Primera Instancia de Circuito de Santa Fe; Rosario; Rafaela; Venado Tuerto; Santo Tom\u00e9; Laguna Paiva; Esperanza; Coronda; Arroyo Seco; G\u00e1lvez; San Crist\u00f3bal; Villa Gobernador G\u00e1lvez; San Justo; San Javier; Ca\u00f1ada de G\u00f3mez; Vera; Ceres; Las Rosas; Reconquista; Villa Ocampo; Casilda; Avellaneda; San Vicente; San Lorenzo; San Genaro; Villa Constituci\u00f3n; El Tr\u00e9bol; Sastre; Sunchales; San Carlos Centro; Helvecia; y Juzgados de Ejecuci\u00f3n de Circuito de Santa Fe y Rosario. La Etapa 2: a implementarse el 5.8.2024, comprende a los expedientes que se inicien en dicha fecha en los Tribunales Colegiados de Familia de Santa Fe y Rosario; los Tribunales Colegiados de Responsabilidad Extracontractual de Santa Fe y Rosario; los Juzgados de Primera Instancia de Distrito de Familia de Venado Tuerto; Reconquista; Rafaela; Vera; Ca\u00f1ada de G\u00f3mez; Casilda; San Lorenzo; San Crist\u00f3bal y Villa Constituci\u00f3n; los Juzgados de Primera Instancia de Distrito en lo Civil, Comercial y Laboral de Ceres; Vera; Casilda; Ca\u00f1ada de G\u00f3mez; San Javier; San Crist\u00f3bal; Tostado; San Justo; San Jorge; Esperanza; Rufino; Villa Ocampo; Melincu\u00e9; y Firmat. La Etapa 3: a implementarse el 2.9.2024, comprende a los expedientes que se inicien en dicha fecha en las C\u00e1maras de Apelaci\u00f3n en lo Civil y Comercial de Santa Fe y Rosario; las C\u00e1maras de Apelaci\u00f3n en lo Civil, Comercial y Laboral de Venado Tuerto; Reconquista; Rafaela; a los Juzgados de Primera Instancia de Distrito en lo Civil y Comercial de Santa Fe; Rosario; Rafaela; Venado Tuerto; Reconquista; San Lorenzo; y Villa Constituci\u00f3n. La Etapa 4: a implementarse el 7.10.2024 comprende a los expedientes que se inicien en dicha fecha en la Secretar\u00eda T\u00e9cnica de la Corte Suprema de Justicia; las C\u00e1maras de Apelaci\u00f3n en lo Laboral de Santa Fe y Rosario; los Juzgados de Primera Instancia de Distrito en lo Laboral de Santa Fe; Rosario; Rafaela; Reconquista; San Lorenzo; Venado Tuerto; Villa Constituci\u00f3n; y C\u00e1maras en lo Contencioso Administrativo de Santa Fe y Rosario. Que asimismo, y a los fines de facilitar la operatoria que aqu\u00ed se propone, desprovista de la materialidad del expediente f\u00edsico, corresponde poner de resalto que se encuentra prevista la dotaci\u00f3n de mayores recursos inform\u00e1ticos en cada puesto de trabajo de los operadores aqu\u00ed involucrados; como as\u00ed tambi\u00e9n, diversas mejoras sist\u00e9micas que surgieran de propuestas efectuados por los representantes de cada fuero en los encuentros celebrados con las Comisiones de Seguimiento de SISFE creados por el Alto Cuerpo mediante Acta Acuerdo Nro. 46 del 2.11.15. Por lo dem\u00e1s, cabe agregar que las causas que a la fecha se encuentran tramitando en soporte papel, y m\u00e1s all\u00e1 de su digitalizaci\u00f3n dentro del sistema de gesti\u00f3n SISFE; conservar\u00e1n y continuar\u00e1n su decurso procesal con su resguardo papel hasta su debida finalizaci\u00f3n. Que, en virtud de lo expuesto, y atento a lo establecido en los art\u00edculos 92 de la Constituci\u00f3n Provincial, 19 y 22 de la Ley N\u00b010160 (t.o. seg\u00fan Decreto N\u00b0 46\/98) y las facultades conferidas por Acuerdo de fecha 20.10.99, Acta N\u00b0 41, Punto \u00danico, la Secretar\u00eda de Gobierno de la Excma. Corte Suprema de Justicia de la Provincia de Santa Fe, <\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\"><u>RESUELVE<\/u><\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">: I. Proponer a la Corte Suprema de Justicia la puesta en marcha de la \u00faltima etapa de la digitalizaci\u00f3n integral del Poder Judicial, en todos los expedientes de todas las unidades jurisdiccionales de los distintos fueros de derecho privado, de conformidad con las etapas y fechas previstas en los considerandos precedentes. II. Requerir a la Corte Suprema de Justicia, se delegue en esta Secretar\u00eda de Gobierno las tareas inherentes para la capacitaci\u00f3n y materializaci\u00f3n de las propuestas aqu\u00ed elevadas. Reg\u00edstrese, res\u00e9rvese copia y d\u00e9se cuenta al Cuerpo. FDO.: BORDAS (SECRETARIO). GOMEZ (PROSECRETARIO)\u201d. O\u00eddo lo cual y de conformidad con lo dictaminado en este acto por el se\u00f1or Procurador General, <\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\"><u>SE RESUELVE<\/u><\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">: I. Hacer lugar a la propuesta formulada por la Secretar\u00eda de Gobierno del Cuerpo. II. Delegar en la Secretar\u00eda de Gobierno las tareas inherentes para la capacitaci\u00f3n y materializaci\u00f3n de lo aqu\u00ed decidido. III. Librar las comunicaciones pertinentes. FDO.: GUTI\u00c9RREZ. ERBETTA. FALISTOCCO. GASTALDI. NETRI. BARRAGUIRRE. BORDAS (SECRETARIO)\u201d.&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Courier New, monospace\"><span style=\"font-size: medium\"><span lang=\"es-AR\">&#8211;<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Times New Roman, serif\"><span style=\"color: #000000\"><span style=\"font-size: medium\"><span lang=\"es-AR\"> Saludo a Ud. atentamente.<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">Dr. Eduardo Bordas<\/p>\n<p align=\"JUSTIFY\">Secretario de Gobierno<\/p>\n<div class=\"gsp_post_data\" data-post_type=\"circulares\" data-cat=\"ano-2024-circulares,circulares\" data-modified=\"120\" data-title=\"Circular nro. 57. \u00daltima etapa de Digitalizaci\u00f3n Integral del Poder Judicial.\" data-home=\"https:\/\/www.justiciasantafe.gov.ar\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Circular Nro. 57\/24.- Santa Fe, 12 de junio de 2024.- Se\u00f1or Titular del \u00d3rgano Jurisdiccional S \/ D Me dirijo a Ud. a fin de comunicarle, para su conocimiento y notificaci\u00f3n a todos los integrantes de ese \u00f3rgano jurisdiccional, que en el Acuerdo celebrado el d\u00eda 11.6.2024, Acta N\u00b0 21, la Corte Suprema de Justicia [&#8230;]\n","protected":false},"author":72,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4113,18],"tags":[],"class_list":["post-41344","circulares","type-circulares","status-publish","format-standard","hentry","category-ano-2024-circulares","category-circulares"],"acf":{"i2t_anio":2024,"i2t_id_historico":"","i2t_autor_historico":""},"_links":{"self":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/41344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares"}],"about":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/circulares"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/72"}],"version-history":[{"count":0,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/41344\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=41344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=41344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=41344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}