 {"id":42319,"date":"2024-09-05T11:59:05","date_gmt":"2024-09-05T14:59:05","guid":{"rendered":"https:\/\/www.justiciasantafe.gov.ar\/?post_type=circulares&#038;p=42319"},"modified":"2024-09-05T11:59:05","modified_gmt":"2024-09-05T14:59:05","slug":"circular-nro-82-llamado-a-concurso-para-cubrir-un-cargo-de-secretario-de-camara-de-circuito-de-los-tribunales-de-rosario","status":"publish","type":"circulares","link":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/circulares\/circular-nro-82-llamado-a-concurso-para-cubrir-un-cargo-de-secretario-de-camara-de-circuito-de-los-tribunales-de-rosario\/","title":{"rendered":"Circular nro. 82. Llamado a concurso para cubrir un cargo de Secretario de C\u00e1mara de Circuito de los Tribunales de Rosario."},"content":{"rendered":"<div class=\"pdfprnt-buttons pdfprnt-buttons-circulares pdfprnt-top-right\"><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/42319?print=pdf\" class=\"pdfprnt-button pdfprnt-button-pdf\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/pdf.png\" alt=\"image_pdf\" title=\"Ver PDF\" \/><\/a><a href=\"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/42319?print=print\" class=\"pdfprnt-button pdfprnt-button-print\" target=\"_blank\"><img decoding=\"async\" src=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/plugins\/pdf-print-pro\/images\/print.png\" alt=\"image_print\" title=\"Imprimir contenido\" \/><\/a><\/div><p align=\"RIGHT\"><span style=\"color: #000000\"><u><b>Circular Nro. 82\/24.-<\/b><\/u><\/span><\/p>\n<p align=\"CENTER\">\n<p align=\"RIGHT\"><span style=\"color: #000000\">Santa Fe, 5 de septiembre de 2024.-<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Se\u00f1or<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Titular del \u00d3rgano Jurisdiccional<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u>S \/ D<\/u><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia de fecha 29.08.2024, ratificada por Acuerdo del Alto Tribunal celebrado el d\u00eda 3 de septiembre de 2024, Acta N\u00b0 33 punto 3, se ha dispuesto llamar a Concurso para la provisi\u00f3n del siguiente cargo:<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>UN CARGO DE SECRETARIO DE CAMARA PARA DESEMPE\u00d1ARSE EN LA CAMARA DE APELACIONES DE CIRCUITO DE LOS TRIBUNALES DE ROSARIO.<\/b><\/u><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>Car\u00e1cter del concurso<\/b><\/u><\/span><span style=\"color: #000000\"><b>:<\/b><\/span><span style=\"color: #000000\"> Abierto, de antecedentes y en su caso de oposici\u00f3n.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>Requisitos:<\/b><\/u><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><b> a)<\/b><\/span><span style=\"color: #000000\"> Poseer ciudadan\u00eda argentina; <\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><b>b)<\/b><\/span><span style=\"color: #000000\"> Mayor\u00eda de edad;<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><b>c)<\/b><\/span><span style=\"color: #000000\"> T\u00edtulo de abogado o escribano, con dos <\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\">a\u00f1os de antig\u00fcedad a la fecha del llamado a concurso;<\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><b>d)<\/b><\/span> <span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">Dos a\u00f1os de residencia inmediata en la Provincia sino hubieren nacido en ella debidamente acreditados<\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\">;<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><b>e)<\/b><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"> Certificaci\u00f3n de la Oficina Judicial correspondiente de no hallarse incluido en el Registro de Deudores Alimentarios <\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\">Morosos;<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><b>f)<\/b><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"> Buenos antecedentes de conducta, acreditados con el Certificado respectivo otorgado por la Polic\u00eda de la Provincia;<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><b>g) <\/b><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-AR\">Constancia del Colegio profesional respectivo de no poseer sanciones en los \u00faltimos diez a\u00f1os para quienes no pertenezcan al Poder Judicial <\/span><\/span><\/span><\/span><span style=\"color: #000000\"><span style=\"font-family: Times New Roman, serif\"><span style=\"font-size: medium\"><span lang=\"es-MX\">(con emisi\u00f3n actualizada a la fecha de inscripci\u00f3n al llamado a concurso);<\/span><\/span><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>Per\u00edodo de inscripci\u00f3n:<\/b><\/u><\/span><span style=\"color: #000000\"> Del 16 al 27 de septiembre de 2024, ambas fechas inclusive, debiendo los interesados presentar las respectivas solicitudes -en el formulario confeccionado al efecto-, ante la Secretar\u00eda Letrada de la Corte Suprema de Justicia en Rosario, mencionando y acompa\u00f1ando, en su caso, todos los antecedentes que estimen convenientes, los que deber\u00e1n ser retirados dentro del plazo de dos meses una vez resuelto el concurso.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>Ex\u00e1menes de oposici\u00f3n<\/b><\/u><\/span><span style=\"color: #000000\"><b>:<\/b><\/span><span style=\"color: #000000\"> En caso de as\u00ed disponerse, oportunamente se designar\u00e1n las fechas para los ex\u00e1menes de oposici\u00f3n.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\"><u><b>Entrevistas Personales<\/b><\/u><\/span><span style=\"color: #000000\"><b>:<\/b><\/span><span style=\"color: #000000\"> Asimismo, en su oportunidad se designar\u00e1 la fecha para la recepci\u00f3n de entrevistas personales a los postulantes inscriptos que re\u00fanan las exigencias legales y reglamentarias.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">El concurso precedente se realizar\u00e1 de acuerdo a las prescripciones contenidas en el Reglamento vigente para la provisi\u00f3n de Cargos de Funcionarios en el Poder Judicial.<\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"color: #000000\">Saludo a Ud. atentamente.<\/span><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">Dr. Eduardo Bordas<\/p>\n<p align=\"JUSTIFY\">Secretario de Gobierno<\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\">Formulario de inscripci\u00f3n:\u00a0 <a href=\"https:\/\/www.justiciasantafe.gov.ar\/wp-content\/uploads\/2024\/09\/CIRC-82-24-ANEXO.pdf\" target=\"\" rel=\"attachment wp-att-42320 noopener\">CIRC-82-24 ANEXO<\/a><\/p>\n<div class=\"gsp_post_data\" data-post_type=\"circulares\" data-cat=\"ano-2024-circulares,circulares\" data-modified=\"120\" data-title=\"Circular nro. 82. Llamado a concurso para cubrir un cargo de Secretario de C\u00e1mara de Circuito de los Tribunales de Rosario.\" data-home=\"https:\/\/www.justiciasantafe.gov.ar\"><\/div>","protected":false},"excerpt":{"rendered":"<p>Circular Nro. 82\/24.- Santa Fe, 5 de septiembre de 2024.- Se\u00f1or Titular del \u00d3rgano Jurisdiccional S \/ D Para su conocimiento y notificaci\u00f3n a los dem\u00e1s integrantes de esa dependencia, me dirijo a Ud. a fin de comunicarle que por resoluci\u00f3n de la Secretar\u00eda de Gobierno de la Corte Suprema de Justicia de la Provincia [&#8230;]\n","protected":false},"author":72,"featured_media":0,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4113,18],"tags":[],"class_list":["post-42319","circulares","type-circulares","status-publish","format-standard","hentry","category-ano-2024-circulares","category-circulares"],"acf":{"i2t_anio":2024,"i2t_id_historico":"","i2t_autor_historico":""},"_links":{"self":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/42319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares"}],"about":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/types\/circulares"}],"author":[{"embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/users\/72"}],"version-history":[{"count":0,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/circulares\/42319\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/media?parent=42319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/categories?post=42319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.justiciasantafe.gov.ar\/index.php\/wp-json\/wp\/v2\/tags?post=42319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}